{"id":37908,"date":"2026-05-12T17:52:39","date_gmt":"2026-05-12T23:52:39","guid":{"rendered":"https:\/\/thepueblatimes.mx\/?p=37908"},"modified":"2026-05-12T17:52:39","modified_gmt":"2026-05-12T23:52:39","slug":"visita-pepe-chedraui-desayunador-escolar-en-el-jardin-de-ninos-la-flor","status":"publish","type":"post","link":"https:\/\/thepueblatimes.mx\/index.php\/2026\/05\/12\/visita-pepe-chedraui-desayunador-escolar-en-el-jardin-de-ninos-la-flor\/","title":{"rendered":"Visita Pepe Chedraui desayunador escolar en el Jard\u00edn de Ni\u00f1os \u00abLa Flor\u00bb"},"content":{"rendered":"<p>Puebla, Pue., 12 de mayo de 2026.\u2013 Con el objetivo de supervisar la calidad de las obras entregadas a beneficio de la ni\u00f1ez poblana, el Gobierno de la Ciudad, que encabeza el alcalde Pepe Chedraui, acudi\u00f3 al Jard\u00edn de Ni\u00f1os \u201cLa Flor\u201d para verificar el buen funcionamiento del desayunador entregado hace unas semanas, como parte del Programa Nacional de Alimentaci\u00f3n Escolar.<\/p>\n<p>Estas acciones forman parte del compromiso de la administraci\u00f3n por trabajar en la conversi\u00f3n de los desayunos fr\u00edos a calientes que se ofrecen en las escuelas de la capital con el objetivo de fortalecer el desempe\u00f1o escolar de los estudiantes a trav\u00e9s del consumo de una alimentaci\u00f3n nutritiva y balanceada.<\/p>\n<p>Asimismo, el presidente municipal Pepe Chedraui y el director general del DIF Puebla Capital, Jes\u00fas Alejandro Cort\u00e9s Carrasco, sostuvieron un acercamiento con directivos escolares y responsables del programa, a fin de constatar el buen funcionamiento y operaci\u00f3n de este espacio alimentario.<\/p>\n<p>De esta forma, el Gobierno de la Ciudad, a trav\u00e9s del DIF Puebla Capital, reafirman su compromiso de fortalecer la seguridad alimentaria desde las escuelas, en beneficio de todas y todos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Puebla, Pue., 12 de mayo de 2026.\u2013 Con el objetivo de supervisar la calidad de las obras entregadas a beneficio de la ni\u00f1ez poblana, el Gobierno de la Ciudad, que encabeza el alcalde Pepe Chedraui, acudi\u00f3 al Jard\u00edn de Ni\u00f1os \u201cLa Flor\u201d para verificar el buen funcionamiento del desayunador entregado hace unas semanas, como parte&#8230;<\/p>\n","protected":false},"author":16,"featured_media":37909,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[20],"tags":[1287,3074],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Visita Pepe Chedraui desayunador escolar en el Jard\u00edn de Ni\u00f1os &quot;La Flor&quot; - The Puebla Times<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thepueblatimes.mx\/index.php\/2026\/05\/12\/visita-pepe-chedraui-desayunador-escolar-en-el-jardin-de-ninos-la-flor\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Visita Pepe Chedraui desayunador escolar en el Jard\u00edn de Ni\u00f1os &quot;La Flor&quot; - The Puebla Times\" \/>\n<meta property=\"og:description\" content=\"Puebla, Pue., 12 de mayo de 2026.\u2013 Con el objetivo de supervisar la calidad de las obras entregadas a beneficio de la ni\u00f1ez poblana, el Gobierno de la Ciudad, que encabeza el alcalde Pepe Chedraui, acudi\u00f3 al Jard\u00edn de Ni\u00f1os \u201cLa Flor\u201d para verificar el buen funcionamiento del desayunador entregado hace unas semanas, como parte...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thepueblatimes.mx\/index.php\/2026\/05\/12\/visita-pepe-chedraui-desayunador-escolar-en-el-jardin-de-ninos-la-flor\/\" \/>\n<meta property=\"og:site_name\" content=\"The Puebla Times\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-12T23:52:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thepueblatimes.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-15.33.10.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sa\u00fal Hern\u00e1ndez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sa\u00fal Hern\u00e1ndez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/thepueblatimes.mx\/index.php\/2026\/05\/12\/visita-pepe-chedraui-desayunador-escolar-en-el-jardin-de-ninos-la-flor\/\",\"url\":\"https:\/\/thepueblatimes.mx\/index.php\/2026\/05\/12\/visita-pepe-chedraui-desayunador-escolar-en-el-jardin-de-ninos-la-flor\/\",\"name\":\"Visita Pepe Chedraui desayunador escolar en el Jard\u00edn de Ni\u00f1os \\\"La Flor\\\" - The Puebla Times\",\"isPartOf\":{\"@id\":\"https:\/\/thepueblatimes.mx\/#website\"},\"datePublished\":\"2026-05-12T23:52:39+00:00\",\"dateModified\":\"2026-05-12T23:52:39+00:00\",\"author\":{\"@id\":\"https:\/\/thepueblatimes.mx\/#\/schema\/person\/1664894c2f65ce2c7a08d8f5f905c13c\"},\"breadcrumb\":{\"@id\":\"https:\/\/thepueblatimes.mx\/index.php\/2026\/05\/12\/visita-pepe-chedraui-desayunador-escolar-en-el-jardin-de-ninos-la-flor\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/thepueblatimes.mx\/index.php\/2026\/05\/12\/visita-pepe-chedraui-desayunador-escolar-en-el-jardin-de-ninos-la-flor\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/thepueblatimes.mx\/index.php\/2026\/05\/12\/visita-pepe-chedraui-desayunador-escolar-en-el-jardin-de-ninos-la-flor\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/thepueblatimes.mx\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Visita Pepe Chedraui desayunador escolar en el Jard\u00edn de Ni\u00f1os \u00abLa Flor\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/thepueblatimes.mx\/#website\",\"url\":\"https:\/\/thepueblatimes.mx\/\",\"name\":\"The Puebla Times\",\"description\":\"Noticias del Estado de Puebla\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/thepueblatimes.mx\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/thepueblatimes.mx\/#\/schema\/person\/1664894c2f65ce2c7a08d8f5f905c13c\",\"name\":\"Sa\u00fal Hern\u00e1ndez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/thepueblatimes.mx\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/11be338693f243309532caad8f10c930?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/11be338693f243309532caad8f10c930?s=96&d=mm&r=g\",\"caption\":\"Sa\u00fal Hern\u00e1ndez\"},\"url\":\"https:\/\/thepueblatimes.mx\/index.php\/author\/saulhernandez\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Visita Pepe Chedraui desayunador escolar en el Jard\u00edn de Ni\u00f1os \"La Flor\" - The Puebla Times","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thepueblatimes.mx\/index.php\/2026\/05\/12\/visita-pepe-chedraui-desayunador-escolar-en-el-jardin-de-ninos-la-flor\/","og_locale":"es_ES","og_type":"article","og_title":"Visita Pepe Chedraui desayunador escolar en el Jard\u00edn de Ni\u00f1os \"La Flor\" - The Puebla Times","og_description":"Puebla, Pue., 12 de mayo de 2026.\u2013 Con el objetivo de supervisar la calidad de las obras entregadas a beneficio de la ni\u00f1ez poblana, el Gobierno de la Ciudad, que encabeza el alcalde Pepe Chedraui, acudi\u00f3 al Jard\u00edn de Ni\u00f1os \u201cLa Flor\u201d para verificar el buen funcionamiento del desayunador entregado hace unas semanas, como parte...","og_url":"https:\/\/thepueblatimes.mx\/index.php\/2026\/05\/12\/visita-pepe-chedraui-desayunador-escolar-en-el-jardin-de-ninos-la-flor\/","og_site_name":"The Puebla Times","article_published_time":"2026-05-12T23:52:39+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/thepueblatimes.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-15.33.10.jpeg","type":"image\/jpeg"}],"author":"Sa\u00fal Hern\u00e1ndez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Sa\u00fal Hern\u00e1ndez","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/thepueblatimes.mx\/index.php\/2026\/05\/12\/visita-pepe-chedraui-desayunador-escolar-en-el-jardin-de-ninos-la-flor\/","url":"https:\/\/thepueblatimes.mx\/index.php\/2026\/05\/12\/visita-pepe-chedraui-desayunador-escolar-en-el-jardin-de-ninos-la-flor\/","name":"Visita Pepe Chedraui desayunador escolar en el Jard\u00edn de Ni\u00f1os \"La Flor\" - The Puebla Times","isPartOf":{"@id":"https:\/\/thepueblatimes.mx\/#website"},"datePublished":"2026-05-12T23:52:39+00:00","dateModified":"2026-05-12T23:52:39+00:00","author":{"@id":"https:\/\/thepueblatimes.mx\/#\/schema\/person\/1664894c2f65ce2c7a08d8f5f905c13c"},"breadcrumb":{"@id":"https:\/\/thepueblatimes.mx\/index.php\/2026\/05\/12\/visita-pepe-chedraui-desayunador-escolar-en-el-jardin-de-ninos-la-flor\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thepueblatimes.mx\/index.php\/2026\/05\/12\/visita-pepe-chedraui-desayunador-escolar-en-el-jardin-de-ninos-la-flor\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/thepueblatimes.mx\/index.php\/2026\/05\/12\/visita-pepe-chedraui-desayunador-escolar-en-el-jardin-de-ninos-la-flor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/thepueblatimes.mx\/"},{"@type":"ListItem","position":2,"name":"Visita Pepe Chedraui desayunador escolar en el Jard\u00edn de Ni\u00f1os \u00abLa Flor\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/thepueblatimes.mx\/#website","url":"https:\/\/thepueblatimes.mx\/","name":"The Puebla Times","description":"Noticias del Estado de Puebla","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thepueblatimes.mx\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/thepueblatimes.mx\/#\/schema\/person\/1664894c2f65ce2c7a08d8f5f905c13c","name":"Sa\u00fal Hern\u00e1ndez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/thepueblatimes.mx\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/11be338693f243309532caad8f10c930?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/11be338693f243309532caad8f10c930?s=96&d=mm&r=g","caption":"Sa\u00fal Hern\u00e1ndez"},"url":"https:\/\/thepueblatimes.mx\/index.php\/author\/saulhernandez\/"}]}},"jetpack_featured_media_url":"https:\/\/thepueblatimes.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-15.33.10.jpeg","_links":{"self":[{"href":"https:\/\/thepueblatimes.mx\/index.php\/wp-json\/wp\/v2\/posts\/37908"}],"collection":[{"href":"https:\/\/thepueblatimes.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thepueblatimes.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thepueblatimes.mx\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/thepueblatimes.mx\/index.php\/wp-json\/wp\/v2\/comments?post=37908"}],"version-history":[{"count":1,"href":"https:\/\/thepueblatimes.mx\/index.php\/wp-json\/wp\/v2\/posts\/37908\/revisions"}],"predecessor-version":[{"id":37910,"href":"https:\/\/thepueblatimes.mx\/index.php\/wp-json\/wp\/v2\/posts\/37908\/revisions\/37910"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thepueblatimes.mx\/index.php\/wp-json\/wp\/v2\/media\/37909"}],"wp:attachment":[{"href":"https:\/\/thepueblatimes.mx\/index.php\/wp-json\/wp\/v2\/media?parent=37908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thepueblatimes.mx\/index.php\/wp-json\/wp\/v2\/categories?post=37908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thepueblatimes.mx\/index.php\/wp-json\/wp\/v2\/tags?post=37908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}