{"id":12965,"date":"2021-04-20T15:09:11","date_gmt":"2021-04-20T20:09:11","guid":{"rendered":"https:\/\/thepueblatimes.mx\/?p=12965"},"modified":"2021-04-20T15:09:11","modified_gmt":"2021-04-20T20:09:11","slug":"asesinan-a-balazos-a-un-trabajador-del-campo-en-xiutetelco","status":"publish","type":"post","link":"https:\/\/thepueblatimes.mx\/index.php\/2021\/04\/20\/asesinan-a-balazos-a-un-trabajador-del-campo-en-xiutetelco\/","title":{"rendered":"Asesinan a balazos a un trabajador del campo en Xiutetelco"},"content":{"rendered":"<div class=\"content-body clearfix \">\n<div id=\"content-body-225-6619768\">\n<p>XIUTETELCO, Pue.- Un hombre fue asesinado a balazos durante la ma\u00f1ana de este lunes al interior de una parcela ubicada dentro de la comunidad de San Antonio.<\/p>\n<p>De acuerdo a lo dado a conocer por la autoridades, con base en lo declarado por sus familiares, el hombre identificado como Rogelio \u201cN\u201d, sali\u00f3 de su domicilio cerca de las 7:00 horas, con rumbo a su parcela, a fin de dar inicio a su jornada laboral, sin embargo al filo de las 9:00 horas fue hallado, por un familiar, con tres impactos de bala por lo que fue trasladado al centro de salud de este lugar.<\/p>\n<\/div>\n<\/div>\n<article class=\"content-continued-body clearfix \">\n<div id=\"content-body-5851641-6619768\">\n<p>Sin embargo tras la revisi\u00f3n por parte del personal del nosocomio, se determin\u00f3 que el hombre carec\u00eda de signos v\u00edtales por lo que se iniciaron las investigaciones correspondientes.<\/p>\n<p>El masculino fue identificado como Rogelio \u201cN\u201d de 39 a\u00f1os de edad, con domicilio en esa misma comunidad de San Antonio, quien perdi\u00f3 la vida a ra\u00edz de tres impactos de bala, motivo por el que autoridades de la Fiscal\u00eda dieron inicio a una carpeta de investigaci\u00f3n, a fin de dar con el posible responsable, del cual hasta el momento se desconoce su paradero.<\/p>\n<\/div>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>XIUTETELCO, Pue.- Un hombre fue asesinado a balazos durante la ma\u00f1ana de este lunes al interior de una parcela ubicada dentro de la comunidad de San Antonio. De acuerdo a lo dado a conocer por la autoridades, con base en lo declarado por sus familiares, el hombre identificado como Rogelio \u201cN\u201d, sali\u00f3 de su domicilio&#8230;<\/p>\n","protected":false},"author":15,"featured_media":12966,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[20],"tags":[169,49],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Asesinan a balazos a un trabajador del campo en Xiutetelco - The Puebla Times<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thepueblatimes.mx\/index.php\/2021\/04\/20\/asesinan-a-balazos-a-un-trabajador-del-campo-en-xiutetelco\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Asesinan a balazos a un trabajador del campo en Xiutetelco - The Puebla Times\" \/>\n<meta property=\"og:description\" content=\"XIUTETELCO, Pue.- Un hombre fue asesinado a balazos durante la ma\u00f1ana de este lunes al interior de una parcela ubicada dentro de la comunidad de San Antonio. De acuerdo a lo dado a conocer por la autoridades, con base en lo declarado por sus familiares, el hombre identificado como Rogelio \u201cN\u201d, sali\u00f3 de su domicilio...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thepueblatimes.mx\/index.php\/2021\/04\/20\/asesinan-a-balazos-a-un-trabajador-del-campo-en-xiutetelco\/\" \/>\n<meta property=\"og:site_name\" content=\"The Puebla Times\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-20T20:09:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thepueblatimes.mx\/wp-content\/uploads\/2021\/04\/Centro-de-Salud-Xiutetelco-muerto-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"479\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francisco S\u00e1nchez Nolasco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francisco S\u00e1nchez Nolasco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/thepueblatimes.mx\/index.php\/2021\/04\/20\/asesinan-a-balazos-a-un-trabajador-del-campo-en-xiutetelco\/\",\"url\":\"https:\/\/thepueblatimes.mx\/index.php\/2021\/04\/20\/asesinan-a-balazos-a-un-trabajador-del-campo-en-xiutetelco\/\",\"name\":\"Asesinan a balazos a un trabajador del campo en Xiutetelco - The Puebla Times\",\"isPartOf\":{\"@id\":\"https:\/\/thepueblatimes.mx\/#website\"},\"datePublished\":\"2021-04-20T20:09:11+00:00\",\"dateModified\":\"2021-04-20T20:09:11+00:00\",\"author\":{\"@id\":\"https:\/\/thepueblatimes.mx\/#\/schema\/person\/7bdf2adbc50078b104bba72b5612f774\"},\"breadcrumb\":{\"@id\":\"https:\/\/thepueblatimes.mx\/index.php\/2021\/04\/20\/asesinan-a-balazos-a-un-trabajador-del-campo-en-xiutetelco\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/thepueblatimes.mx\/index.php\/2021\/04\/20\/asesinan-a-balazos-a-un-trabajador-del-campo-en-xiutetelco\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/thepueblatimes.mx\/index.php\/2021\/04\/20\/asesinan-a-balazos-a-un-trabajador-del-campo-en-xiutetelco\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/thepueblatimes.mx\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Asesinan a balazos a un trabajador del campo en Xiutetelco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/thepueblatimes.mx\/#website\",\"url\":\"https:\/\/thepueblatimes.mx\/\",\"name\":\"The Puebla Times\",\"description\":\"Noticias del Estado de Puebla\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/thepueblatimes.mx\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/thepueblatimes.mx\/#\/schema\/person\/7bdf2adbc50078b104bba72b5612f774\",\"name\":\"Francisco S\u00e1nchez Nolasco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/thepueblatimes.mx\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6061d7d20b38bc2742a5218401b198d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6061d7d20b38bc2742a5218401b198d2?s=96&d=mm&r=g\",\"caption\":\"Francisco S\u00e1nchez Nolasco\"},\"url\":\"https:\/\/thepueblatimes.mx\/index.php\/author\/marianitha-reyes\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Asesinan a balazos a un trabajador del campo en Xiutetelco - The Puebla Times","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thepueblatimes.mx\/index.php\/2021\/04\/20\/asesinan-a-balazos-a-un-trabajador-del-campo-en-xiutetelco\/","og_locale":"es_ES","og_type":"article","og_title":"Asesinan a balazos a un trabajador del campo en Xiutetelco - The Puebla Times","og_description":"XIUTETELCO, Pue.- Un hombre fue asesinado a balazos durante la ma\u00f1ana de este lunes al interior de una parcela ubicada dentro de la comunidad de San Antonio. De acuerdo a lo dado a conocer por la autoridades, con base en lo declarado por sus familiares, el hombre identificado como Rogelio \u201cN\u201d, sali\u00f3 de su domicilio...","og_url":"https:\/\/thepueblatimes.mx\/index.php\/2021\/04\/20\/asesinan-a-balazos-a-un-trabajador-del-campo-en-xiutetelco\/","og_site_name":"The Puebla Times","article_published_time":"2021-04-20T20:09:11+00:00","og_image":[{"width":768,"height":479,"url":"https:\/\/thepueblatimes.mx\/wp-content\/uploads\/2021\/04\/Centro-de-Salud-Xiutetelco-muerto-01.jpg","type":"image\/jpeg"}],"author":"Francisco S\u00e1nchez Nolasco","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Francisco S\u00e1nchez Nolasco","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/thepueblatimes.mx\/index.php\/2021\/04\/20\/asesinan-a-balazos-a-un-trabajador-del-campo-en-xiutetelco\/","url":"https:\/\/thepueblatimes.mx\/index.php\/2021\/04\/20\/asesinan-a-balazos-a-un-trabajador-del-campo-en-xiutetelco\/","name":"Asesinan a balazos a un trabajador del campo en Xiutetelco - The Puebla Times","isPartOf":{"@id":"https:\/\/thepueblatimes.mx\/#website"},"datePublished":"2021-04-20T20:09:11+00:00","dateModified":"2021-04-20T20:09:11+00:00","author":{"@id":"https:\/\/thepueblatimes.mx\/#\/schema\/person\/7bdf2adbc50078b104bba72b5612f774"},"breadcrumb":{"@id":"https:\/\/thepueblatimes.mx\/index.php\/2021\/04\/20\/asesinan-a-balazos-a-un-trabajador-del-campo-en-xiutetelco\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thepueblatimes.mx\/index.php\/2021\/04\/20\/asesinan-a-balazos-a-un-trabajador-del-campo-en-xiutetelco\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/thepueblatimes.mx\/index.php\/2021\/04\/20\/asesinan-a-balazos-a-un-trabajador-del-campo-en-xiutetelco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/thepueblatimes.mx\/"},{"@type":"ListItem","position":2,"name":"Asesinan a balazos a un trabajador del campo en Xiutetelco"}]},{"@type":"WebSite","@id":"https:\/\/thepueblatimes.mx\/#website","url":"https:\/\/thepueblatimes.mx\/","name":"The Puebla Times","description":"Noticias del Estado de Puebla","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thepueblatimes.mx\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/thepueblatimes.mx\/#\/schema\/person\/7bdf2adbc50078b104bba72b5612f774","name":"Francisco S\u00e1nchez Nolasco","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/thepueblatimes.mx\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6061d7d20b38bc2742a5218401b198d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6061d7d20b38bc2742a5218401b198d2?s=96&d=mm&r=g","caption":"Francisco S\u00e1nchez Nolasco"},"url":"https:\/\/thepueblatimes.mx\/index.php\/author\/marianitha-reyes\/"}]}},"jetpack_featured_media_url":"https:\/\/thepueblatimes.mx\/wp-content\/uploads\/2021\/04\/Centro-de-Salud-Xiutetelco-muerto-01.jpg","_links":{"self":[{"href":"https:\/\/thepueblatimes.mx\/index.php\/wp-json\/wp\/v2\/posts\/12965"}],"collection":[{"href":"https:\/\/thepueblatimes.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thepueblatimes.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thepueblatimes.mx\/index.php\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/thepueblatimes.mx\/index.php\/wp-json\/wp\/v2\/comments?post=12965"}],"version-history":[{"count":1,"href":"https:\/\/thepueblatimes.mx\/index.php\/wp-json\/wp\/v2\/posts\/12965\/revisions"}],"predecessor-version":[{"id":12967,"href":"https:\/\/thepueblatimes.mx\/index.php\/wp-json\/wp\/v2\/posts\/12965\/revisions\/12967"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thepueblatimes.mx\/index.php\/wp-json\/wp\/v2\/media\/12966"}],"wp:attachment":[{"href":"https:\/\/thepueblatimes.mx\/index.php\/wp-json\/wp\/v2\/media?parent=12965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thepueblatimes.mx\/index.php\/wp-json\/wp\/v2\/categories?post=12965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thepueblatimes.mx\/index.php\/wp-json\/wp\/v2\/tags?post=12965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}